{"id":4969,"date":"2014-02-28T11:13:40","date_gmt":"2014-02-28T10:13:40","guid":{"rendered":"http:\/\/ndijdiqr.preview.infomaniak.website\/de\/contact\/"},"modified":"2026-03-13T14:25:05","modified_gmt":"2026-03-13T13:25:05","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/hotelnegociants.ch\/de\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2149.5500345625555!2d6.841816515565357!3d46.45960775061514!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x478e9cd1e5d5ed3d%3A0x580a8e23a15b34fc!2sH%C3%B4tel-Restaurant+les+N%C3%A9gociants!5e0!3m2!1sfr!2sch!4v1473254863358\" width=\"1440\" height=\"350\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: left;\">Kontaktieren Sie uns<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4379-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"4379\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/4969#wpcf7-f4379-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4379\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4379-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Votre nom (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre e-mail (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Sujet<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"quiz\"><label><span class=\"wpcf7-quiz-label\">5 + 5 =<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz\" value=\"57e68f7c4a5186f3d7c59ab712d245d3\" \/><\/span><\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: left;\">Adresse<\/h1>\n<p><strong>H\u00f4tel Restaurant Les N\u00e9gociants<\/strong><br \/>\nRue du Conseil 27<br \/>\n1800 Vevey<br \/>\nSwitzerland<\/p>\n<p><a href=\"mailto:info@hotelnegociants.ch\" target=\"_blank\" rel=\"noopener noreferrer\">info@hotelnegociants.ch<\/a><\/p>\n<p><strong>Tel\u00a0:<\/strong><strong>+41 21 922 70 11<\/strong><br \/>\nFax : +41 21 921 34 24<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\">Restaurant-Zeiten<\/h1>\n<table class=\"opening_hours_table\">\n<tbody>\n<tr>\n<th><\/th>\n<th>Mittag<\/th>\n<th>Abend<\/th>\n<\/tr>\n<tr>\n<th>Dienstag bis Samstag<\/th>\n<td>11h30-14h00<\/td>\n<td style=\"text-align: left;\">18h15-22h00<\/td>\n<\/tr>\n<tr>\n<th>Sonntag &amp; Montag<\/th>\n<td>geschlossen<\/td>\n<td>geschlossen<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_appear appear vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-3d vc_btn3-block vc_btn3-icon-left vc_btn3-color-inverse\" href=\"http:\/\/www.hotelnegociants.ch\/de\/einen-tisch-reservieren\/\" title=\"\"><i class=\"vc_btn3-icon fa fa-info-circle\"><\/i> Tisch Reservieren<\/a><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Kontaktieren Sie uns Votre nom (obligatoire) Votre e-mail (obligatoire) Sujet Votre message 5 + 5 = Adresse H\u00f4tel Restaurant Les N\u00e9gociants Rue du Conseil 27 1800 Vevey Switzerland info@hotelnegociants.ch Tel\u00a0:+41 21 922 70 11 Fax : +41 21 921 34 [...]","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-4969","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/pages\/4969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/comments?post=4969"}],"version-history":[{"count":6,"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/pages\/4969\/revisions"}],"predecessor-version":[{"id":9400,"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/pages\/4969\/revisions\/9400"}],"wp:attachment":[{"href":"https:\/\/hotelnegociants.ch\/de\/wp-json\/wp\/v2\/media?parent=4969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}